{"id":3017,"date":"2020-03-10T14:56:10","date_gmt":"2020-03-10T12:56:10","guid":{"rendered":"https:\/\/libshop.paris\/?p=3017"},"modified":"2021-04-19T18:27:28","modified_gmt":"2021-04-19T16:27:28","slug":"%e4%bb%a3%e5%b0%94%e5%8d%a1%e6%8b%89%e8%b4%9d%e7%89%b9%e6%a2%85%e9%87%8c","status":"publish","type":"post","link":"https:\/\/libshop.fr\/zh\/deir-el-qalaa-beit-mery\/","title":{"rendered":"\u4ee3\u5c14\u5361\u62c9 (Beit Mery)"},"content":{"rendered":"<div id=\"libsh-30529012\" class=\"libsh-avant-le-contenu libsh-entity-placement\"><div style=\"background: #F7F3EF; padding: 14px; margin-bottom: 34px; margin-top: 34px; box-shadow: 0px 0px 48px 0px rgb(0 0 0 \/ 11%);\">  \n  \n  <div class=\"\n    mailpoet_form_popup_overlay\n      \"><\/div>\n  <div\n    id=\"mailpoet_form_1\"\n    class=\"\n      mailpoet_form\n      mailpoet_form_shortcode\n      mailpoet_form_position_\n      mailpoet_form_animation_\n    \"\n      >\n\n    <style type=\"text\/css\">\n     #mailpoet_form_1 .mailpoet_form {  }\n#mailpoet_form_1 form { margin-bottom: 0; }\n#mailpoet_form_1 .mailpoet_column_with_background { padding: 0px; }\n#mailpoet_form_1 .mailpoet_form_column:not(:first-child) { padding: 0 20px; }\n#mailpoet_form_1 .mailpoet_form_column:not(:first-child) { margin-left: 0; }\n#mailpoet_form_1 h2.mailpoet-heading { margin: 0 0 20px 0; }\n#mailpoet_form_1 .mailpoet_paragraph { line-height: 20px; margin-bottom: 20px; }\n#mailpoet_form_1 .mailpoet_segment_label, #mailpoet_form_1 .mailpoet_text_label, #mailpoet_form_1 .mailpoet_textarea_label, #mailpoet_form_1 .mailpoet_select_label, #mailpoet_form_1 .mailpoet_radio_label, #mailpoet_form_1 .mailpoet_checkbox_label, #mailpoet_form_1 .mailpoet_list_label, #mailpoet_form_1 .mailpoet_date_label { display: block; font-weight: normal; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea, #mailpoet_form_1 .mailpoet_select, #mailpoet_form_1 .mailpoet_date_month, #mailpoet_form_1 .mailpoet_date_day, #mailpoet_form_1 .mailpoet_date_year, #mailpoet_form_1 .mailpoet_date { display: block; }\n#mailpoet_form_1 .mailpoet_text, #mailpoet_form_1 .mailpoet_textarea { width: 200px; }\n#mailpoet_form_1 .mailpoet_checkbox {  }\n#mailpoet_form_1 .mailpoet_submit {  }\n#mailpoet_form_1 .mailpoet_divider {  }\n#mailpoet_form_1 .mailpoet_message {  }\n#mailpoet_form_1 .mailpoet_form_loading { width: 30px; text-align: center; line-height: normal; }\n#mailpoet_form_1 .mailpoet_form_loading > span { width: 5px; height: 5px; background-color: #5b5b5b; }#mailpoet_form_1{border-radius: 0px;color: #1e1e1e;text-align: left;}#mailpoet_form_1 form.mailpoet_form {padding: 14px;}#mailpoet_form_1{width: 87%;}#mailpoet_form_1 .mailpoet_message {margin: 0; padding: 0 20px;}\n        #mailpoet_form_1 .mailpoet_validate_success {color: #00d084}\n        #mailpoet_form_1 input.parsley-success {color: #00d084}\n        #mailpoet_form_1 select.parsley-success {color: #00d084}\n        #mailpoet_form_1 textarea.parsley-success {color: #00d084}\n      \n        #mailpoet_form_1 .mailpoet_validate_error {color: #cf2e2e}\n        #mailpoet_form_1 input.parsley-error {color: #cf2e2e}\n        #mailpoet_form_1 select.parsley-error {color: #cf2e2e}\n        #mailpoet_form_1 textarea.textarea.parsley-error {color: #cf2e2e}\n        #mailpoet_form_1 .parsley-errors-list {color: #cf2e2e}\n        #mailpoet_form_1 .parsley-required {color: #cf2e2e}\n        #mailpoet_form_1 .parsley-custom-error-message {color: #cf2e2e}\n      #mailpoet_form_1 .mailpoet_paragraph.last {margin-bottom: 0} @media (max-width: 500px) {#mailpoet_form_1 {background-image: none;}} @media (min-width: 500px) {#mailpoet_form_1 .last .mailpoet_paragraph:last-child {margin-bottom: 0}}  @media (max-width: 500px) {#mailpoet_form_1 .mailpoet_form_column:last-child .mailpoet_paragraph:last-child {margin-bottom: 0}} \n    <\/style>\n\n    <form\n      target=\"_self\"\n      method=\"post\"\n      action=\"https:\/\/libshop.fr\/wp-admin\/admin-post.php?action=mailpoet_subscription_form\"\n      class=\"mailpoet_form mailpoet_form_form mailpoet_form_shortcode\"\n      novalidate\n      data-delay=\"\"\n      data-exit-intent-enabled=\"\"\n      data-trigger-mode=\"\"\n      data-click-trigger-selector=\"\"\n      data-font-family=\"\"\n      data-cookie-expiration-time=\"\"\n    >\n      <input type=\"hidden\" name=\"data[form_id]\" value=\"1\" \/>\n      <input type=\"hidden\" name=\"token\" value=\"047b82152f\" \/>\n      <input type=\"hidden\" name=\"api_version\" value=\"v1\" \/>\n      <input type=\"hidden\" name=\"endpoint\" value=\"subscribers\" \/>\n      <input type=\"hidden\" name=\"mailpoet_method\" value=\"subscribe\" \/>\n\n      <label class=\"mailpoet_hp_email_label\" style=\"display: none !important;\">Please leave this field empty<input type=\"email\" name=\"data[email]\"\/><\/label><h2 class=\"mailpoet-heading  mailpoet-has-font-size\" style=\"text-align: left; color: #8ed1fc; font-size: 32px\"><strong><span class=\"has-inline-color has-black-color\">Ne manquez plus aucun<\/span> code promo<\/strong><\/h2>\n<p class=\"mailpoet_form_paragraph  mailpoet-has-font-size\" style=\"text-align: left; color: #1e1e1e; font-size: 17px\"><span style=\"font-family: Cairo\" data-font=\"Cairo\" class=\"mailpoet-has-font\"><strong>Inscrivez-vous<\/strong> \u00e0 la newsletter pour recevoir <\/span>chaque mois nos codes promos et nos secrets de nutrition par mail \u2728<\/p>\n<div class=\"mailpoet_paragraph \"><style>input[name=\"data[form_field_MmQ2YzEyNjhkOGU3X2VtYWls]\"]::placeholder{color:#000000;opacity: 1;}<\/style><input type=\"email\" autocomplete=\"email\" class=\"mailpoet_text\" id=\"form_email_1\" name=\"data[form_field_MmQ2YzEyNjhkOGU3X2VtYWls]\" title=\"Adresse e-mail\" value=\"\" style=\"width:100%;box-sizing:border-box;background-color:#ffffff;border-style:solid;border-radius:0px !important;border-width:1px;border-color:#313131;padding:9px;margin: 0 auto 0 0;font-family:&#039;Cairo&#039;;font-size:16px;line-height:1.5;height:auto;color:#000000;\" data-automation-id=\"form_email\"  placeholder=\"Adresse e-mail *\" aria-label=\"Adresse e-mail *\" data-parsley-errors-container=\".mailpoet_error_41zsq\" data-parsley-required=\"true\" required aria-required=\"true\" data-parsley-minlength=\"6\" data-parsley-maxlength=\"150\" data-parsley-type-message=\"This value should be a valid email.\" data-parsley-required-message=\"This field is required.\"\/><span class=\"mailpoet_error_41zsq\"><\/span><\/div>\n<div class=\"mailpoet_paragraph \"><input type=\"submit\" class=\"mailpoet_submit\" value=\"S&#039;abonner \u27f6\" data-automation-id=\"subscribe-submit-button\" data-font-family='Cairo' style=\"width:100%;box-sizing:border-box;background-color:#8ed1fc;border-style:solid;border-radius:5px !important;border-width:0px;border-color:#313131;padding:10px;margin: 0 auto 0 0;font-family:&#039;Cairo&#039;;font-size:15px;line-height:1.5;height:auto;color:#ffffff;font-weight:bold;\" \/><span class=\"mailpoet_form_loading\"><span class=\"mailpoet_bounce1\"><\/span><span class=\"mailpoet_bounce2\"><\/span><span class=\"mailpoet_bounce3\"><\/span><\/span><\/div>\n<p class=\"mailpoet_form_paragraph  mailpoet-has-font-size\" style=\"text-align: left; color: #1e1e1e; font-size: 15px\"><span style=\"font-family: Cairo\" data-font=\"Cairo\" class=\"mailpoet-has-font\">Nous ne spammons pas\u00a0! Consultez notre <a href=\"https:\/\/libshop.fr\/politique-de-confidentialite\/\" data-type=\"URL\" data-id=\"https:\/\/libshop.fr\/politique-de-confidentialite\/\">politique de confidentialit\u00e9<\/a> pour plus d\u2019informations.<\/span><\/p>\n\n      <div class=\"mailpoet_message\">\n        <p class=\"mailpoet_validate_success\"\n                style=\"display:none;\"\n                >V\u00e9rifiez votre boite de r\u00e9ception ou votre r\u00e9pertoire d\u2019ind\u00e9sirables pour confirmer votre abonnement.\n        <\/p>\n        <p class=\"mailpoet_validate_error\"\n                style=\"display:none;\"\n                >        <\/p>\n      <\/div>\n    <\/form>\n\n      <\/div>\n\n  <\/div>\n<\/div><p>Un beau jour se l\u00e8ve \u00e0 nouveau sous le soleil libanais. L\u2019occasion id\u00e9ale pour partir \u00e0 la d\u00e9couverte d\u2019un nouveau village marqu\u00e9 par l\u2019histoire du Liban. Situ\u00e9 en montagne, Beit Mery est \u00e0 la fois un village et une station baln\u00e9aire estivale. Un site touristique qui vaut le d\u00e9tour parce qu\u2019il abrite un des plus beaux vestiges patrimoniaux du Liban, Deir al Qalaa.<\/p>\n<p>https:\/\/www.instagram.com\/p\/BZOfSFUFp-0\/<\/p>\n<p>https:\/\/www.instagram.com\/p\/BYsRb40FMd0\/<\/p>\n<p>Deir al-Qalaa est une \u00e9glise du monast\u00e8re de Saint Jean Baptiste, construite initialement en 1750 sur les ruines d\u2019un ancien temple romain. Situ\u00e9 \u00e0 800 m d\u2019altitude, \u00e0 la p\u00e9riph\u00e9rie Est de l\u2019agglom\u00e9ration beyrouthine, \u00e0 l\u2019entr\u00e9e du village de Beit Mery, le site offre une vue imprenable sur la capitale.<\/p>\n<p>https:\/\/www.instagram.com\/p\/BSpyXVFDVKS\/<\/p>\n<p>https:\/\/www.instagram.com\/p\/ykI5fLi4fO\/<\/p>\n<p>Avant de devenir ce qu\u2019elle est aujourd\u2019hui, un vestige du pass\u00e9, l\u2019\u00e9glise du monast\u00e8re de Saint jean Baptiste a vu toute une succession de constructions-destructions. D\u2019abord une premi\u00e8re \u00e9glise qui fut d\u00e9truite, puis une nouvelle construction en 1768, puis une autre au XIXe si\u00e8cle bas\u00e9e sur les restes de la structure de la seconde \u00e9glise.<\/p>\n<p>https:\/\/www.instagram.com\/p\/BYkYnUdgRj2\/<\/p>\n<p>https:\/\/www.instagram.com\/p\/BvEsXungg_y\/<\/p>\n<p>De l\u2019ancien temple romain, il reste aujourd\u2019hui des blocs massifs qui forment la fondation de l\u2019\u00e9glise. Ce temple, d\u00e9di\u00e9 au grand dieu Baal Marqod, date du Ier si\u00e8cle de notre \u00e8re. Il s\u2019agit du troisi\u00e8me temple le plus large au Liban apr\u00e8s Baalbek et Niha. Le monument fait exactement 40 m de long sur 17 m de large. Aujourd\u2019hui, on peut encore observer sur place, quelques colonnes de l\u2019ancienne fa\u00e7ade du temple. D\u2019un diam\u00e8tre de 1,65 m, elles ornent majestueusement la plateforme am\u00e9nag\u00e9e devant l\u2019entr\u00e9e de l\u2019\u00e9glise.<\/p>\n<p>https:\/\/www.instagram.com\/p\/BSPDbuFBb_6\/<\/p>\n<p>https:\/\/www.instagram.com\/p\/BpbjQGdDBcf\/<\/p>\n<p>Un ensemble cultuel compos\u00e9 de petits temples se trouvent en contrebas du monast\u00e8re. A savoir le temple d\u00e9di\u00e9 \u00e0 Junon, avatar d\u2019une Astart\u00e9 ph\u00e9nicienne \u00e9rig\u00e9 sous le r\u00e8gne de Trajan (98-117). Les deux sites sont s\u00e9par\u00e9s par une porte monumentale. Selon une inscription latine visible sur les lieux, cette porte a \u00e9t\u00e9 \u00e9rig\u00e9e en l\u2019honneur de l\u2019empereur Trajanus (117-198 avant J.C)<\/p>\n<p>https:\/\/www.instagram.com\/p\/BUV-QBxl87J\/<\/p>\n<p>Juste en face de ces temples, on retrouve les ruines d\u2019une cit\u00e9 byzantine (Ve et Vie si\u00e8cle). Ce sont celles d\u2019une \u00e9glise pav\u00e9e de mosa\u00efques, restaur\u00e9e au VIe si\u00e8cle sous le r\u00e8gne de Justinien. Juste \u00e0 c\u00f4t\u00e9 de l\u2019\u00e9glise se trouve les restes de thermes romains. Une partie du sol, d\u00e9truite, laisse appara\u00eetre les colonnes form\u00e9es de disques de c\u00e9ramiques.<\/p>\n<p>https:\/\/www.instagram.com\/p\/Bpjr33HDBC5\/<\/p>\n<p>A l\u2019\u00e9poque romaine, la cit\u00e9 \u00e9tait compos\u00e9e de ruelles dall\u00e9es bord\u00e9es de portiques qui donnaient directement sur des boutiques. Certains quartiers r\u00e9sidentiels sont encore visibles, ainsi que des pressoirs. Les ruelles quant \u00e0 elles sont compos\u00e9es d\u2019un syst\u00e8me de canalisation pour permettre le drainage. Le site est accessible au grand public.<\/p>\n<div id=\"libsh-145429856\" class=\"libsh-apres-le-contenu libsh-entity-placement\"><div style=\"background: #fff9f6; padding: 20px; margin-top: 34px; margin-bottom: 34px; box-shadow: 0px 0px 48px 0px rgb(0 0 0 \/ 11%);\">\n<p style=\"text-align: center;\">\u2728<\/p>\n<p style=\"text-align: center; font-size: 18px;\"><strong>Libshop \u2014 M<\/strong><strong>ezz\u00e9s, shawarmas, falafels, houmous et p\u00e2tisseries d\u2019inspiration libanaise<\/strong> depuis plus de 10 ans.<\/p>\n<p style=\"text-align: center; font-size: 22px;\"><em>\ud83d\udc49 <strong><a href=\"https:\/\/libshop.fr\/reservation\/\">R\u00e9servez votre table dans l&rsquo;un de nos restaurants \u00e0 Paris<\/a><br \/>\n<\/strong>\ud83d\udc49 <strong><a href=\"https:\/\/commande.libshop.fr\/\" target=\"_blank\">Commandez Libshop en click&amp;collect ou en livraison<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: center;\">\u2728<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u9ece\u5df4\u5ae9\u7684\u9633\u5149\u4e0b\uff0c\u53c8\u8fce\u6765\u4e86\u7f8e\u597d\u7684\u4e00\u5929\u3002\u8fd9\u662f\u63a2\u7d22\u8fd9\u5ea7\u627f\u8f7d\u7740\u9ece\u5df4\u5ae9\u5386\u53f2\u5370\u8bb0\u7684\u65b0\u6751\u5e84\u7684\u7edd\u4f73\u673a\u4f1a\u3002\u8d1d\u7279\u6885\u91cc\u5750\u843d\u5728\u7fa4\u5c71\u4e4b\u4e2d\uff0c\u65e2\u662f\u6751\u5e84\uff0c\u4e5f\u662f\u907f\u6691\u80dc\u5730\u3002\u8fd9\u91cc\u503c\u5f97\u7ed5\u9053\u800c\u884c\uff0c\u56e0\u4e3a\u8fd9\u91cc\u62e5\u6709\u9ece\u5df4\u5ae9\u6700\u7f8e\u4e3d\u7684\u9057\u4ea7\u4e4b\u4e00\u2014\u2014\u4ee3\u5c14\u5361\u62c9\u3002https:\/\/www.instagram.com\/p\/BZOfSFUFp-0\/ https:\/\/www.instagram.com\/p\/BYsRb40FMd0\/ \u4ee3\u5c14\u5361\u62c9\u662f\u5723\u7ea6\u7ff0\u6d17\u793c\u8005\u4fee\u9053\u9662\u7684\u4e00\u5ea7\u6559\u5802\uff0c\u6700\u521d\u5efa\u4e8e1750\u5e74\uff0c\u4f4d\u4e8e\u4e00\u5ea7\u53e4\u7f57\u9a6c\u795e\u5e99\u7684\u9057\u5740\u4e0a\u3002<\/p>","protected":false,"raw":"Un beau jour se l\u00e8ve \u00e0 nouveau sous le soleil libanais. L\u2019occasion id\u00e9ale pour partir \u00e0 la d\u00e9couverte d\u2019un nouveau village marqu\u00e9 par l\u2019histoire du Liban. Situ\u00e9 en montagne, Beit Mery est \u00e0 la fois un village et une station baln\u00e9aire estivale. Un site touristique qui vaut le d\u00e9tour parce qu\u2019il abrite un des plus beaux vestiges patrimoniaux du Liban, Deir al Qalaa. https:\/\/www.instagram.com\/p\/BZOfSFUFp-0\/ https:\/\/www.instagram.com\/p\/BYsRb40FMd0\/ Deir al-Qalaa est une \u00e9glise du monast\u00e8re de Saint Jean Baptiste, construite initialement en 1750 sur les ruines d\u2019un ancien temple romain."},"author":1,"featured_media":3019,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"page_builder":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-3017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paysages"],"_links":{"self":[{"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/posts\/3017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/comments?post=3017"}],"version-history":[{"count":1,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/posts\/3017\/revisions"}],"predecessor-version":[{"id":4754,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/posts\/3017\/revisions\/4754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/media\/3019"}],"wp:attachment":[{"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/media?parent=3017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/categories?post=3017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/libshop.fr\/zh\/wp-json\/wp\/v2\/tags?post=3017"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}